{"id":100299,"date":"2025-07-11T22:49:41","date_gmt":"2025-07-11T19:49:41","guid":{"rendered":"https:\/\/shop.hator.gg\/?post_type=product&#038;p=100299"},"modified":"2026-05-07T17:08:03","modified_gmt":"2026-05-07T14:08:03","slug":"hator-hyperpunk-3x-wireless-esh14-black","status":"publish","type":"product","link":"https:\/\/shop.hator.gg\/de\/headsets\/hator-hyperpunk-3x-wireless-esh14-black\/","title":{"rendered":"HATOR Hyperpunk 3X Wireless (ESH14) Black"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"HATOR Hyperpunk 3X Wireless ist ein kabelloses Gaming-Headset, das Hi-Res-Audio, lange Akkulaufzeit und vielseitige Anschlussm\u00f6glichkeiten vereint. Mit 40-mm-Treibern, ClearScan\u2122-Technologie und komfortablem Design bietet dieses Headset ein intensives Spielerlebnis oder Musikh\u00f6ren auf verschiedenen Ger\u00e4ten.","protected":false},"featured_media":139834,"template":"","meta":[],"translation":{"provider":"WPGlobus","version":"2.5.11","language":"de","enabled_languages":["en","ua","de","pl"],"languages":{"en":{"title":true,"content":false,"excerpt":true},"ua":{"title":false,"content":false,"excerpt":true},"de":{"title":false,"content":false,"excerpt":true},"pl":{"title":false,"content":false,"excerpt":true}}},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/shop.hator.gg\/de\/wp-json\/wp\/v2\/product\/100299"}],"collection":[{"href":"https:\/\/shop.hator.gg\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.hator.gg\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.hator.gg\/de\/wp-json\/wp\/v2\/media\/139834"}],"wp:attachment":[{"href":"https:\/\/shop.hator.gg\/de\/wp-json\/wp\/v2\/media?parent=100299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}